{"id":93,"date":"2014-09-22T18:03:14","date_gmt":"2014-09-22T18:03:14","guid":{"rendered":"http:\/\/wp.andreas.bieri.name\/myblog\/?p=93"},"modified":"2014-09-22T18:03:14","modified_gmt":"2014-09-22T18:03:14","slug":"raspberry-pi-und-enocean-teil-2-temperaturmessung","status":"publish","type":"post","link":"http:\/\/52.29.166.97\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/","title":{"rendered":"Raspberry PI und enOcean: Teil 3 Temperaturmessung"},"content":{"rendered":"<p>Teil 1 des Artikels: <a href=\"http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/06\/03\/raspberry-pi-und-enocean-teil-1-ubersicht\/\">http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/06\/03\/raspberry-pi-und-enocean-teil-1-ubersicht\/<\/a><br \/>\nTeil 2 des Artikels: <a href=\"http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/10\/01\/raspberry-pi-und-enocean-teil-2-enocean-funkmodul-und-fhem\/\">http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/10\/01\/raspberry-pi-und-enocean-teil-2-enocean-funkmodul-und-fhem\/<\/a><\/p>\n<p>Als Nachtrag zum ersten Blog noch die realisierte Temperaturmessung auf meinem Balkon mit einem enOcean Sensor: der Sensor ist mit einer Solarzelle gespiesen und wurde wasserdicht in einem &#8222;Petling&#8220; verpackt. Nat\u00fcrlich hat man etwas ein Problem, wenn man die Temperatur im Schatten ohne Sonneneinstrahlung messen sollte und gleichzeitig Licht f\u00fcr den Strom braucht&#8230;die Messdaten werden per Funk (868MHz) zum Raspberry PI im Haus geschickt und mit der Software FHEM visualisiert.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-95\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/eno1.png\" alt=\"eno1\" width=\"709\" height=\"283\" srcset=\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2016\/03\/eno1.png 709w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2016\/03\/eno1-300x120.png 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-94\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/eno2.png\" alt=\"eno2\" width=\"1024\" height=\"357\" srcset=\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2016\/03\/eno2.png 1024w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2016\/03\/eno2-300x105.png 300w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2016\/03\/eno2-768x268.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teil 1 des Artikels: http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/06\/03\/raspberry-pi-und-enocean-teil-1-ubersicht\/ Teil 2 des Artikels: http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/10\/01\/raspberry-pi-und-enocean-teil-2-enocean-funkmodul-und-fhem\/ Als Nachtrag zum ersten Blog noch die realisierte Temperaturmessung auf meinem Balkon mit einem enOcean Sensor: der Sensor ist mit einer Solarzelle gespiesen und wurde wasserdicht in einem &#8222;Petling&#8220; verpackt. Nat\u00fcrlich hat man etwas ein Problem, wenn man die Temperatur im Schatten ohne Sonneneinstrahlung messen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,12],"tags":[45,47],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Raspberry PI und enOcean: Teil 3 Temperaturmessung - Merkbar.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raspberry PI und enOcean: Teil 3 Temperaturmessung - Merkbar.\" \/>\n<meta property=\"og:description\" content=\"Teil 1 des Artikels: http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/06\/03\/raspberry-pi-und-enocean-teil-1-ubersicht\/ Teil 2 des Artikels: http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/10\/01\/raspberry-pi-und-enocean-teil-2-enocean-funkmodul-und-fhem\/ Als Nachtrag zum ersten Blog noch die realisierte Temperaturmessung auf meinem Balkon mit einem enOcean Sensor: der Sensor ist mit einer Solarzelle gespiesen und wurde wasserdicht in einem &#8222;Petling&#8220; verpackt. Nat\u00fcrlich hat man etwas ein Problem, wenn man die Temperatur im Schatten ohne Sonneneinstrahlung messen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkbar.\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-22T18:03:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/eno1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_blogadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\",\"url\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\",\"name\":\"Merkbar.\",\"description\":\"IT, Elektronik und Mathematik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/eno1.png\",\"contentUrl\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/eno1.png\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#webpage\",\"url\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/\",\"name\":\"Raspberry PI und enOcean: Teil 3 Temperaturmessung - Merkbar.\",\"isPartOf\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#primaryimage\"},\"datePublished\":\"2014-09-22T18:03:14+00:00\",\"dateModified\":\"2014-09-22T18:03:14+00:00\",\"author\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\"},\"breadcrumb\":{\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raspberry PI und enOcean: Teil 3 Temperaturmessung\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\",\"name\":\"wp_blogadmin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"caption\":\"wp_blogadmin\"},\"url\":\"http:\/\/52.29.166.97\/myblog\/author\/wp_blogadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raspberry PI und enOcean: Teil 3 Temperaturmessung - Merkbar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/","og_locale":"de_DE","og_type":"article","og_title":"Raspberry PI und enOcean: Teil 3 Temperaturmessung - Merkbar.","og_description":"Teil 1 des Artikels: http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/06\/03\/raspberry-pi-und-enocean-teil-1-ubersicht\/ Teil 2 des Artikels: http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2014\/10\/01\/raspberry-pi-und-enocean-teil-2-enocean-funkmodul-und-fhem\/ Als Nachtrag zum ersten Blog noch die realisierte Temperaturmessung auf meinem Balkon mit einem enOcean Sensor: der Sensor ist mit einer Solarzelle gespiesen und wurde wasserdicht in einem &#8222;Petling&#8220; verpackt. Nat\u00fcrlich hat man etwas ein Problem, wenn man die Temperatur im Schatten ohne Sonneneinstrahlung messen [&hellip;]","og_url":"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/","og_site_name":"Merkbar.","article_published_time":"2014-09-22T18:03:14+00:00","og_image":[{"url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/eno1.png"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"wp_blogadmin","Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website","url":"https:\/\/wp.andreas.bieri.name\/myblog\/","name":"Merkbar.","description":"IT, Elektronik und Mathematik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#primaryimage","inLanguage":"de","url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/eno1.png","contentUrl":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/eno1.png"},{"@type":"WebPage","@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#webpage","url":"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/","name":"Raspberry PI und enOcean: Teil 3 Temperaturmessung - Merkbar.","isPartOf":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#primaryimage"},"datePublished":"2014-09-22T18:03:14+00:00","dateModified":"2014-09-22T18:03:14+00:00","author":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d"},"breadcrumb":{"@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2014\/09\/22\/raspberry-pi-und-enocean-teil-2-temperaturmessung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wp.andreas.bieri.name\/myblog\/"},{"@type":"ListItem","position":2,"name":"Raspberry PI und enOcean: Teil 3 Temperaturmessung"}]},{"@type":"Person","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d","name":"wp_blogadmin","image":{"@type":"ImageObject","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo","inLanguage":"de","url":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","caption":"wp_blogadmin"},"url":"http:\/\/52.29.166.97\/myblog\/author\/wp_blogadmin\/"}]}},"_links":{"self":[{"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/posts\/93"}],"collection":[{"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/comments?post=93"}],"version-history":[{"count":0,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/posts\/93\/revisions"}],"wp:attachment":[{"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/media?parent=93"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/categories?post=93"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/tags?post=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}