{"id":4145,"date":"2025-07-29T17:22:41","date_gmt":"2025-07-29T16:22:41","guid":{"rendered":"http:\/\/wp.andreas.bieri.name\/myblog\/?p=4145"},"modified":"2025-06-28T19:04:12","modified_gmt":"2025-06-28T18:04:12","slug":"die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen","status":"publish","type":"post","link":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/","title":{"rendered":"Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen)"},"content":{"rendered":"<h4>Logik praktisch<\/h4>\n<p>Alle Theorie ist grau. Darum mache ich mit Schulklassen gerne praktische Experimente, die das Funktionieren von theoretischen Konzepten zeigen. Ich qu\u00e4lte sie zuerst mit mathematischer Logik. dann l\u00f6sten wir logische Quizspiele und als Abschluss bastelten wir mit logischen Gattern Schaltungen. Die LEDs leuchten dann eben richtig oder nicht \ud83d\ude42 Es gibt wenig Diskussionen, ob eine L\u00f6sung so halb oder fast oder wirklich richtig ist.<\/p>\n<p>Das Vorgehen:<\/p>\n<ul>\n<li>Zuerst mit Papier und Bleistift (naja, heute mit Pen und Laptop) die Situation verstehen<\/li>\n<li>logische Zusammenh\u00e4nge vereinfachen (Elektroniker kennen das, Karnaugh-Diagramme)<\/li>\n<li>Simulation vor dem Aufbau (z.B. online mit Circuitverse)<\/li>\n<li>Aufbau mit TTL-ICs der Serie 74xx.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>Schaltungsideen<\/h4>\n<p>Als Schaltungsideen nehme ich zuerst Aufgaben vom NAND-Game (nandgame.org) und meine eigenen \u00dcbungen aus dem Unterricht. Danach geht es dann an bin\u00e4re Addierschaltungen, weil sie die bin\u00e4re Addition vorher gelernt haben. Sie haben den Vorteil, dass man gleiche Schaltungen hat, die man zusammenschliessen kann z.B. zu einem 8-Bit-Addierer &#8211; ein gemeinsames Produkt der ganzen Klasse.<\/p>\n<p>&nbsp;<\/p>\n<h4>Impressionen<\/h4>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-4149\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2025\/07\/adder-1.jpg\" alt=\"\" width=\"600\" height=\"326\" srcset=\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1.jpg 948w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1-300x163.jpg 300w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1-768x417.jpg 768w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1-830x451.jpg 830w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1-230x125.jpg 230w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1-350x190.jpg 350w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1-480x261.jpg 480w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-4150\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2025\/07\/adder-2.jpg\" alt=\"\" width=\"600\" height=\"441\" srcset=\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-2.jpg 1436w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-2-300x221.jpg 300w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-2-1024x753.jpg 1024w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-2-768x565.jpg 768w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-2-830x610.jpg 830w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-2-230x169.jpg 230w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-2-350x257.jpg 350w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-2-480x353.jpg 480w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-4151\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2025\/07\/adder-3.jpg\" alt=\"\" width=\"600\" height=\"425\" srcset=\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-3.jpg 1382w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-3-300x213.jpg 300w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-3-1024x725.jpg 1024w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-3-768x544.jpg 768w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-3-830x588.jpg 830w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-3-230x163.jpg 230w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-3-350x248.jpg 350w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-3-480x340.jpg 480w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-4152\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2025\/07\/adder-4.jpg\" alt=\"\" width=\"600\" height=\"484\" srcset=\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-4.jpg 1173w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-4-300x242.jpg 300w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-4-1024x827.jpg 1024w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-4-768x620.jpg 768w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-4-830x670.jpg 830w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-4-230x186.jpg 230w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-4-350x283.jpg 350w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-4-480x388.jpg 480w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Aufr\u00e4umen<\/h4>\n<p>Am Ende muss ziemlich viel Material auseinandergenommen, sortiert und gepr\u00fcft werden. Daf\u00fcr habe ich einen einfachen Tester mit einem Mikrocontroller gebaut. Damit kann man schnell klar defekte ICs aussortieren (manche Beschriftungen kann man auch mit einer Lupe kaum lesen).<\/p>\n<p>Bauteile:<\/p>\n<ul>\n<li>Arduino Nano (dieser hat gerade genug Pins)<\/li>\n<li>Adafruit LCD Backpack zur Anbindung mit I2C<\/li>\n<li>Zero-Force Sockel<\/li>\n<li>modifizierter Code von Dan Nelson<\/li>\n<\/ul>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-4160\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3.jpg\" alt=\"\" width=\"600\" height=\"393\" srcset=\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3.jpg 1769w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3-300x197.jpg 300w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3-1024x671.jpg 1024w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3-768x503.jpg 768w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3-1536x1006.jpg 1536w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3-830x544.jpg 830w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3-230x151.jpg 230w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3-350x229.jpg 350w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester3-480x314.jpg 480w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"size-full wp-image-4148 aligncenter\" src=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester2-e1751133696363.jpg\" alt=\"\" width=\"469\" height=\"198\" srcset=\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester2-e1751133696363.jpg 469w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester2-e1751133696363-300x127.jpg 300w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester2-e1751133696363-230x97.jpg 230w, http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/ttl-tester2-e1751133696363-350x148.jpg 350w\" sizes=\"(max-width: 469px) 100vw, 469px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fazit:<\/strong> 3 von ca. 80 waren defekt (in vierter war mir schon optisch aufgefallen und wurde aussortiert). Doch, der kleine Aufwand f\u00fcr den Tester hat sich gelohnt.<\/p>\n<p>&nbsp;<\/p>\n<h4>Links<\/h4>\n<ul>\n<li>Circuitverse <a href=\"https:\/\/circuitverse.org\/\" target=\"_blank\" rel=\"noopener\">https:\/\/circuitverse.org\/<\/a><\/li>\n<li>NAND-Game <a href=\"https:\/\/nandgame.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/nandgame.com\/<\/a><\/li>\n<li>Ben Eater: Build an 8-bit CPU from scratch <a href=\"https:\/\/eater.net\/\" target=\"_blank\" rel=\"noopener\">https:\/\/eater.net\/<\/a><\/li>\n<li>Arduino Chip Tester <a href=\"https:\/\/github.com\/DanNelson\/Arduino-TTL-IC-Tester\" target=\"_blank\" rel=\"noopener\">https:\/\/github.com\/DanNelson\/Arduino-TTL-IC-Tester<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Logik praktisch Alle Theorie ist grau. Darum mache ich mit Schulklassen gerne praktische Experimente, die das Funktionieren von theoretischen Konzepten zeigen. Ich qu\u00e4lte sie zuerst mit mathematischer Logik. dann l\u00f6sten wir logische Quizspiele und als Abschluss bastelten wir mit logischen Gattern Schaltungen. Die LEDs leuchten dann eben richtig oder nicht \ud83d\ude42 Es gibt wenig Diskussionen, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13,11],"tags":[189],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen) - Merkbar.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen) - Merkbar.\" \/>\n<meta property=\"og:description\" content=\"Logik praktisch Alle Theorie ist grau. Darum mache ich mit Schulklassen gerne praktische Experimente, die das Funktionieren von theoretischen Konzepten zeigen. Ich qu\u00e4lte sie zuerst mit mathematischer Logik. dann l\u00f6sten wir logische Quizspiele und als Abschluss bastelten wir mit logischen Gattern Schaltungen. Die LEDs leuchten dann eben richtig oder nicht \ud83d\ude42 Es gibt wenig Diskussionen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkbar.\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T16:22:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-28T18:04:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2025\/07\/adder-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_blogadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\",\"url\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\",\"name\":\"Merkbar.\",\"description\":\"IT, Elektronik und Mathematik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1.jpg\",\"contentUrl\":\"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1.jpg\",\"width\":948,\"height\":515},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#webpage\",\"url\":\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/\",\"name\":\"Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen) - Merkbar.\",\"isPartOf\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#primaryimage\"},\"datePublished\":\"2025-07-29T16:22:41+00:00\",\"dateModified\":\"2025-06-28T18:04:12+00:00\",\"author\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\"},\"breadcrumb\":{\"@id\":\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen)\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\",\"name\":\"wp_blogadmin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"caption\":\"wp_blogadmin\"},\"url\":\"http:\/\/52.29.166.97\/myblog\/author\/wp_blogadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen) - Merkbar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/","og_locale":"de_DE","og_type":"article","og_title":"Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen) - Merkbar.","og_description":"Logik praktisch Alle Theorie ist grau. Darum mache ich mit Schulklassen gerne praktische Experimente, die das Funktionieren von theoretischen Konzepten zeigen. Ich qu\u00e4lte sie zuerst mit mathematischer Logik. dann l\u00f6sten wir logische Quizspiele und als Abschluss bastelten wir mit logischen Gattern Schaltungen. Die LEDs leuchten dann eben richtig oder nicht \ud83d\ude42 Es gibt wenig Diskussionen, [&hellip;]","og_url":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/","og_site_name":"Merkbar.","article_published_time":"2025-07-29T16:22:41+00:00","article_modified_time":"2025-06-28T18:04:12+00:00","og_image":[{"url":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2025\/07\/adder-1.jpg"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"wp_blogadmin","Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website","url":"https:\/\/wp.andreas.bieri.name\/myblog\/","name":"Merkbar.","description":"IT, Elektronik und Mathematik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#primaryimage","inLanguage":"de","url":"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1.jpg","contentUrl":"http:\/\/52.29.166.97\/myblog\/wp-content\/uploads\/2025\/07\/adder-1.jpg","width":948,"height":515},{"@type":"WebPage","@id":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#webpage","url":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/","name":"Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen) - Merkbar.","isPartOf":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#primaryimage"},"datePublished":"2025-07-29T16:22:41+00:00","dateModified":"2025-06-28T18:04:12+00:00","author":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d"},"breadcrumb":{"@id":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/52.29.166.97\/myblog\/2025\/07\/29\/die-guten-ins-toepfchen-oder-ttl-gatter-massenweise-pruefen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wp.andreas.bieri.name\/myblog\/"},{"@type":"ListItem","position":2,"name":"Die guten ins T\u00f6pfchen (oder: TTL Gatter massenweise pr\u00fcfen)"}]},{"@type":"Person","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d","name":"wp_blogadmin","image":{"@type":"ImageObject","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo","inLanguage":"de","url":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","caption":"wp_blogadmin"},"url":"http:\/\/52.29.166.97\/myblog\/author\/wp_blogadmin\/"}]}},"_links":{"self":[{"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/posts\/4145"}],"collection":[{"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/comments?post=4145"}],"version-history":[{"count":9,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/posts\/4145\/revisions"}],"predecessor-version":[{"id":4162,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/posts\/4145\/revisions\/4162"}],"wp:attachment":[{"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/media?parent=4145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/categories?post=4145"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.29.166.97\/myblog\/wp-json\/wp\/v2\/tags?post=4145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}